{"id":1255,"count":3,"description":"","link":"https:\/\/blog.goticketly.com\/index.php\/category\/delhi\/","name":"Delhi","slug":"delhi","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blog.goticketly.com\/index.php\/wp-json\/wp\/v2\/categories\/1255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.goticketly.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.goticketly.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.goticketly.com\/index.php\/wp-json\/wp\/v2\/posts?categories=1255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}